{"id":15347,"date":"2017-12-25T18:12:48","date_gmt":"2017-12-25T17:12:48","guid":{"rendered":"http:\/\/mundgericht.de\/?p=15347"},"modified":"2017-12-25T18:12:48","modified_gmt":"2017-12-25T17:12:48","slug":"rindergulasch-mit-ananas","status":"publish","type":"post","link":"https:\/\/mundgericht.de\/index.php\/rindergulasch-mit-ananas\/","title":{"rendered":"Rindergulasch mit Ananas"},"content":{"rendered":"<p><a href=\"http:\/\/mundgericht.de\/wp-content\/uploads\/2017\/12\/Rindergulasch-mit-Ananas_ji-W800.jpg\" rel=\"lightbox[15347]\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-15348\" src=\"http:\/\/mundgericht.de\/wp-content\/uploads\/2017\/12\/Rindergulasch-mit-Ananas_ji-W800.jpg\" alt=\"\" width=\"510\" height=\"340\" srcset=\"https:\/\/mundgericht.de\/wp-content\/uploads\/2017\/12\/Rindergulasch-mit-Ananas_ji-W800.jpg 800w, https:\/\/mundgericht.de\/wp-content\/uploads\/2017\/12\/Rindergulasch-mit-Ananas_ji-W800-300x200.jpg 300w, https:\/\/mundgericht.de\/wp-content\/uploads\/2017\/12\/Rindergulasch-mit-Ananas_ji-W800-768x512.jpg 768w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/a><\/p>\n<p>Die Kombination von Fleisch und Ananas habe ich als Jugendlicher das erste Mal in einem damals noch sehr exotischen chinesischen Restaurant kennengelernt. Bald darauf hielt die Ananas, begleitet von Mangos und Avocados, Einzug in deutsche K\u00fcchen.<\/p>\n<p><!--more--><\/p>\n<p><strong>1 kg Rindergulasch<\/strong><\/p>\n<p><strong>150 gr. durchwachsener Speck<\/strong><\/p>\n<p><strong>3 Zwiebeln<\/strong><\/p>\n<p><strong>2 rote Paprikaschoten<\/strong><\/p>\n<p><strong>2 Stangen Porree<\/strong><\/p>\n<p><strong>250 gr. Champignons<\/strong><\/p>\n<p><strong>2 rote Chilischoten<\/strong><\/p>\n<p><strong>\u00bd Ananas<\/strong><\/p>\n<p><strong>200 ml Gem\u00fcsebr\u00fche<\/strong><\/p>\n<p><strong>100 gr. Cr\u00e8me Fra\u00eeche<\/strong><\/p>\n<p><strong>3 EL Raps\u00f6l<\/strong><\/p>\n<p><strong>Pfeffer<\/strong><\/p>\n<p><strong>Salz<\/strong><\/p>\n<p><em><strong>\u00a0<\/strong><\/em><\/p>\n<p>Den Speck und die gew\u00fcrfelten Zwiebeln mit den Rindergulaschw\u00fcrfeln im Raps\u00f6l in einem Br\u00e4ter anbraten. Dann die gew\u00fcrfelten Paprikaschoten, die in Ringe geschnittenen Chilischoten, die halbierten Champignons und den in kurze Stangen geschnittenen Porree dazugeben. Gut vermischen und weiter anbraten. Mit der Gem\u00fcsebr\u00fche abl\u00f6schen und die in kleine St\u00fccke geschnittene Ananas beif\u00fcgen. Bei geschlossenem Deckel im Backofen bei 160 Grad 2 Stunden gar kochen. Abschlie\u00dfend die Cr\u00e8me Fra\u00eeche unterr\u00fchren.<\/p>\n<p>Wem Das Gulasch zu fl\u00fcssig ist, der kann mit Mehl oder Speisest\u00e4rke andicken.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kombination von Fleisch und Ananas habe ich als Jugendlicher das erste Mal in einem damals noch sehr exotischen chinesischen Restaurant kennengelernt. Bald darauf hielt die Ananas, begleitet von Mangos und Avocados, Einzug in deutsche K\u00fcchen.<\/p>\n","protected":false},"author":2,"featured_media":15348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[178,13],"tags":[474,21,207,577,537,159,470,536,510,806,403],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/posts\/15347"}],"collection":[{"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/comments?post=15347"}],"version-history":[{"count":1,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/posts\/15347\/revisions"}],"predecessor-version":[{"id":15349,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/posts\/15347\/revisions\/15349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/media\/15348"}],"wp:attachment":[{"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/media?parent=15347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/categories?post=15347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundgericht.de\/index.php\/wp-json\/wp\/v2\/tags?post=15347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}